{"id":2031,"date":"2026-02-15T14:42:29","date_gmt":"2026-02-15T14:42:29","guid":{"rendered":"https:\/\/nielsgadechamberorchestra.de\/?page_id=2031"},"modified":"2026-02-15T15:15:05","modified_gmt":"2026-02-15T15:15:05","slug":"elisaweta-oreschkow","status":"publish","type":"page","link":"https:\/\/nielsgadechamberorchestra.de\/en\/main-page\/ngco\/members\/elisaweta-oreschkow\/","title":{"rendered":"Elisaweta Oreschkow"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Elisaweta Oreschkow<\/h2>","protected":false},"excerpt":{"rendered":"<p>Elisaweta Oreschkow<\/p>","protected":false},"author":1,"featured_media":1995,"parent":209,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"enable","_kad_post_title":"hide","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"boxed","_kad_post_vertical_padding":"","_kad_post_feature":"show","_kad_post_feature_position":"default","_kad_post_header":true,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2031","page","type-page","status-publish","has-post-thumbnail","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/pages\/2031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/comments?post=2031"}],"version-history":[{"count":2,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/pages\/2031\/revisions"}],"predecessor-version":[{"id":2036,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/pages\/2031\/revisions\/2036"}],"up":[{"embeddable":true,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/pages\/209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/media\/1995"}],"wp:attachment":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/media?parent=2031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}