{"id":1736,"date":"2026-01-18T19:15:39","date_gmt":"2026-01-18T19:15:39","guid":{"rendered":"https:\/\/nielsgadechamberorchestra.de\/?post_type=tribe_events&#038;p=1736"},"modified":"2026-05-13T08:58:40","modified_gmt":"2026-05-13T08:58:40","slug":"hoert-hoert-schaetze-der-musikbibliothek-peters-iv","status":"publish","type":"tribe_events","link":"https:\/\/nielsgadechamberorchestra.de\/en\/evento\/hoert-hoert-schaetze-der-musikbibliothek-peters-iv\/","title":{"rendered":"H\u00f6rt h\u00f6rt! Sch\u00e4tze der Musikbibliothek Peters (IV)! &#8222;STIMMEN EINER UNRUHIGEN WELT&#8220;"},"content":{"rendered":"<p data-start=\"0\" data-end=\"32\"><strong data-start=\"0\" data-end=\"32\">STIMMEN EINER UNRUHIGEN WELT<\/strong><\/p>\n<p data-start=\"34\" data-end=\"385\">F. Mendelssohn &#8211; Jauchzet dem Herrn alle Welt (Psalm 100)<br \/>\nA. Rubinstein &#8211; Streichquartett in F-moll, op. 17 nr. 3<br \/>\nE. Schulhoff &#8211; Divertimento, op. 14<br \/>\nF. Mendelssohn &#8211; Warum toben die Heiden (Psalm 2)<\/p>\n<p data-start=\"34\" data-end=\"385\">Dieses Programm vereint Werke, die aus sehr unterschiedlichen Zeiten und Perspektiven auf eine gemeinsame Erfahrung blicken: das Leben in einer Welt voller Spannung, Bewegung und Ver\u00e4nderung. Zwischen spiritueller Kraft, pers\u00f6nlichem Ausdruck und musikalischer Rebellion entsteht ein vielschichtiger Dialog \u00fcber Gemeinschaft, Konflikt und Identit\u00e4t.<\/p>\n<p data-start=\"387\" data-end=\"822\">Mendelssohns Psalmen verleihen kollektiven Emotionen eine Stimme \u2013 zwischen Lobpreis, Dramatik und existenzieller Energie. Rubinsteins Streichquartett richtet den Blick nach innen und zeigt die romantische Suche nach Intensit\u00e4t und Wahrheit. Schulhoff wiederum durchbricht traditionelle Klangvorstellungen mit scharfen Rhythmen, t\u00e4nzerischer Direktheit und einer Musik, die sp\u00fcrbar von den Umbr\u00fcchen des 20. Jahrhunderts gepr\u00e4gt ist.<\/p>\n<p data-start=\"824\" data-end=\"956\" data-is-last-node=\"\" data-is-only-node=\"\">Gemeinsam zeichnen diese Werke das Bild einer unruhigen Welt \u2013 und von Menschen, die versuchen, darin ihren eigenen Klang zu finden.<\/p>\n<p data-start=\"824\" data-end=\"956\" data-is-last-node=\"\" data-is-only-node=\"\">Niels Gade Chamber Orchestra<\/p>","protected":false},"excerpt":{"rendered":"<p>F. Mendelssohn &#8211; Jauchzet dem Herrn alle Welt (Psalm 100)<br \/>\nA. Rubinstein &#8211; Streichquartett in F-moll, op. 17 nr. 3<br \/>\nE. Schulhoff &#8211; Divertimento, op. 14<br \/>\nF. Mendelssohn &#8211; Warum toben die Heiden (Psalm 2)<\/p>","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1736","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/tribe_events\/1736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":5,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/tribe_events\/1736\/revisions"}],"predecessor-version":[{"id":2228,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/tribe_events\/1736\/revisions\/2228"}],"wp:attachment":[{"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/media?parent=1736"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/tags?post=1736"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/nielsgadechamberorchestra.de\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=1736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}